﻿{"id":6181,"date":"2010-07-29T09:12:00","date_gmt":"2010-07-29T07:12:00","guid":{"rendered":"https:\/\/www.paris-chartres.fr\/blog\/les-feuilles-mortes-deja\/"},"modified":"2010-07-29T09:12:00","modified_gmt":"2010-07-29T07:12:00","slug":"les-feuilles-mortes-deja","status":"publish","type":"post","link":"https:\/\/www.paris-chartres.fr\/blog\/les-feuilles-mortes-deja\/","title":{"rendered":"Les Feuilles mortes d\u00e9ja?!!"},"content":{"rendered":"<!--Ads0--><div>\n<p><span lang=FR>Un train en panne du c\u00f4t\u00e9 de Bretoncelles ce matin&#8230;\u00a0 Bretoncelles, le triangle des Bermudes de la ligne; que se passe t&#8217;il&nbsp;: Des feuilles mortes, un feu de talus, un troupeau d&#8217;\u00e9l\u00e9phants?? \u00c0 moins que ce ne soit la faute de RFF, de Bruxelles et des ses directives?!<o:p><\/o:p><\/span><\/p>\n<p><span lang=FR>On nous indique que l&#8217;on peut esp\u00e9rer \u00eatre \u00e0 Paris vers 10h15 en attendant un hypoth\u00e9tique d\u00e9part vers 8h55 de Chartres! Ou bien, faut&#8217; il prendre ce car pour Rambouillet dont on nous parle par haut-parleur??<o:p><\/o:p><\/span><\/p>\n<p><span lang=FR>Un car pour Rambouillet&nbsp;; la SNCF a donc abandonn\u00e9e le transport ferroviaire?!<o:p><\/o:p><\/span><\/p>\n<p><span lang=FR>Moi je veux aller de Chartres \u00e0 Paris en 1h maximum&#8230;<o:p><\/o:p><\/span><\/p>\n<p><span lang=FR>INCOMP\u00c9TENCE, INCOMP\u00c9TENCE&#8230;<o:p><\/o:p><\/span><\/p>\n<p><span lang=FR><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p><span lang=FR>Merci la SNCF, merci la r\u00e9gion Centre.<o:p><\/o:p><\/span><\/p>\n<p><span lang=FR><o:p>&nbsp;<\/o:p><\/span><\/p>\n<p><span lang=FR>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 -FL-<\/span><o:p><\/o:p><\/p>\n<p><o:p>&nbsp;<\/o:p><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Un train en panne du c\u00f4t\u00e9 de Bretoncelles ce matin&#8230;\u00a0 Bretoncelles, le triangle des Bermudes de la ligne; que se passe t&#8217;il&nbsp;: Des feuilles mortes,&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/posts\/6181"}],"collection":[{"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/comments?post=6181"}],"version-history":[{"count":0,"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/posts\/6181\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/media?parent=6181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/categories?post=6181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/tags?post=6181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}