﻿{"id":6194,"date":"2010-07-27T00:37:00","date_gmt":"2010-07-26T22:37:00","guid":{"rendered":"https:\/\/www.paris-chartres.fr\/blog\/retards-repetes-et-perte-demploi-pas-que-chez-nous\/"},"modified":"2010-07-27T00:37:00","modified_gmt":"2010-07-26T22:37:00","slug":"retards-repetes-et-perte-demploi-pas-que-chez-nous","status":"publish","type":"post","link":"https:\/\/www.paris-chartres.fr\/blog\/retards-repetes-et-perte-demploi-pas-que-chez-nous\/","title":{"rendered":"Retards r\u00e9p\u00e9t\u00e9s et perte d&#8217;emploi&#8230; pas que \u00ab\u00a0chez nous\u00a0\u00bb&#8230;"},"content":{"rendered":"<!--Ads0--><p>Selon <a href=\"http:\/\/www.20minutes.fr\/article\/586399\/Lyon-Une-jeune-femme-perd-son-premier-emploi-en-raison-de-retards-repetes-sur-sa-ligne-de-train-SNCF.php\">20 minutes<\/a>, une jeune femme en p&eacute;riode d&rsquo;essai s&rsquo;est faite remerci&eacute;e &agrave; cause des retards r&eacute;p&eacute;t&eacute;s sur la ligne Lyon &#8211; Amb&eacute;rieu (180 retards de plus de 10 minutes entre juin et juillet sur cette ligne). Apr&egrave;s un mois et demi d&rsquo;essai &agrave; un poste d&rsquo;assistante juridique, son patron a jug&eacute; que ce n&rsquo;&eacute;tait plus tenable. Elle avait fini par prendre une heure de marge, en prenant un train arrivant &agrave; Lyon &agrave; 7h49 pour une prise de poste &agrave; 9h&#8230;. Bonjour la fatigue ! <\/p>\n<p> L&rsquo;association de d&eacute;fense des usagers du TER Lyon-Amb&eacute;rieu (Adula) envisage de porter plainte contre la SNCF afin de&nbsp; r&eacute;clamer des dommages et int&eacute;r&ecirc;ts pour Soazig, pr&eacute;nom de la jeune femme en question.<\/p>\n<p> Affaire &agrave; suivre&#8230; J&rsquo;ai entendu parler plusieurs fois de licenciements ou des patrons refusant d&#8217;embaucher du personnel du 28. Si plainte est d&eacute;pos&eacute;e et\/ou gain de cause obtenu, les usagers sur \u00ab\u00a0notre\u00a0\u00bb ligne victimes de licenciements notamment, pourraient embo&icirc;ter le pas afin d&rsquo;obtenir gain de cause eux aussi des pr&eacute;judices subis !<\/p>\n<div align=\"right\">Mael <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Selon 20 minutes, une jeune femme en p&eacute;riode d&rsquo;essai s&rsquo;est faite remerci&eacute;e &agrave; cause des retards r&eacute;p&eacute;t&eacute;s sur la ligne Lyon &#8211; Amb&eacute;rieu (180 retards&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/posts\/6194"}],"collection":[{"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/comments?post=6194"}],"version-history":[{"count":0,"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/posts\/6194\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/media?parent=6194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/categories?post=6194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/tags?post=6194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}