﻿{"id":6250,"date":"2010-06-28T12:21:00","date_gmt":"2010-06-28T10:21:00","guid":{"rendered":"https:\/\/www.paris-chartres.fr\/blog\/vos-avis\/"},"modified":"2010-06-28T12:21:00","modified_gmt":"2010-06-28T10:21:00","slug":"vos-avis","status":"publish","type":"post","link":"https:\/\/www.paris-chartres.fr\/blog\/vos-avis\/","title":{"rendered":"Vos avis"},"content":{"rendered":"<!--Ads0--><p>Bonjour,<br \/>\u00a0<br \/>En raison des prix exhorbitant dans l&#39;immobili\u00e9 parisien (dans Paris plus petite couronne) pour une qualit\u00e9 de vie pas des plus terribles, mon amie et moi pensons nous \u00e9loigner un peu. Rambouillet est un choix possible \u00e9tant donn\u00e9 que mon amie travail \u00e0 Montparnasse. J&#39;ai bien conscience de participer \u00e0 la hausse du prix de l&#39;immobilier \u00e0 Rambouillet, mais que ce soit \u00e0 Paris ou Rambouillet il faut bien se loger quelque part.<br \/> Je suis avec attention le traffic. Il est vrai que les retards sont fr\u00e9quents, mais \u00e7a n&#39;est pas non plus tous les jours, tous les trains.<br \/>Comme on dit souvent, on entend plus les gens se plaindre que ceux qui sont satisfait. C&#39;est pourquoi j&#39;aimerais avoir diff\u00e9rents avis. Etes vous globalement satisfait? Je sais que nombreux sont ceux ayant habit\u00e9 \u00e0 Paris, regretez vous ce choix? Reviendriez vous en arri\u00e8re (si oui peut \u00eatre bient\u00f4t un appartement \u00e0 vendre \ud83d\ude42 )?<br \/> \u00a0<br \/>Les train de 8h15 et 8h27 sont il blind\u00e9s ou trouve t&#39;on encore des places assises \u00e0 Rambouillet?<br \/>Derni\u00e8re question: accepteriez vous qu&#39;on vous pose des questions \u00e0 ce sujet \u00e0 Montparnasse \u00e0 la descente du train (une option que l&#39;on a envisag\u00e9, mais bon je me dis que le matin les gens n&#39;ont peut \u00eatre pas envie qu&#39;on les emerdes avec ces questions.<br \/> \u00a0<br \/>Je vous remercie si vous pouviez me r\u00e9pondre sinc\u00e8rement. Peut \u00eatre une fa\u00e7on de donner la parole \u00e0 ceux qui n&#39;ont pas envie de se plaindre (je critique pas les autres, ont est tous comme \u00e7a), et les autres afin de prendre un peu de recul (malgr\u00e9 les plaintes \u00eates vous quand m\u00eame heureux de ce choix)<br \/> \u00a0<br \/>Merci pour vos retours<br \/>\u00a0<br \/>Emmanuel<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonjour,\u00a0En raison des prix exhorbitant dans l&#39;immobili\u00e9 parisien (dans Paris plus petite couronne) pour une qualit\u00e9 de vie pas des plus terribles, mon amie et&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/posts\/6250"}],"collection":[{"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/comments?post=6250"}],"version-history":[{"count":0,"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/posts\/6250\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/media?parent=6250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/categories?post=6250"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/tags?post=6250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}