﻿{"id":6966,"date":"2009-12-08T19:35:00","date_gmt":"2009-12-08T18:35:00","guid":{"rendered":"https:\/\/www.paris-chartres.fr\/blog\/service-infotrafic-872\/"},"modified":"2009-12-08T19:35:00","modified_gmt":"2009-12-08T18:35:00","slug":"service-infotrafic-872","status":"publish","type":"post","link":"https:\/\/www.paris-chartres.fr\/blog\/service-infotrafic-872\/","title":{"rendered":"Service Infotrafic"},"content":{"rendered":"<p>Le train 16759 &#8211; d\u00e9part : gare de Paris-Montparnasse &#8211; \u00e0 18:25 &#8211; Arriv\u00e9e \u00e0 : gare de Le Mans &#8211; 20:43 aura un retard de 25mn environ &#8211; Difficult\u00e9s lors de la pr\u00e9paration du train<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le train 16759 &#8211; d\u00e9part : gare de Paris-Montparnasse &#8211; \u00e0 18:25 &#8211; Arriv\u00e9e \u00e0 : gare de Le Mans &#8211; 20:43 aura un retard&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/posts\/6966"}],"collection":[{"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/comments?post=6966"}],"version-history":[{"count":0,"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/posts\/6966\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/media?parent=6966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/categories?post=6966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paris-chartres.fr\/blog\/wp-json\/wp\/v2\/tags?post=6966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}